{"id":7706,"date":"2020-02-21T20:21:23","date_gmt":"2020-02-22T00:21:23","guid":{"rendered":"http:\/\/www.notaoficial.com\/s\/?p=7706"},"modified":"2020-02-21T20:21:23","modified_gmt":"2020-02-22T00:21:23","slug":"cines-unidos-incluye-nuevo-metodo-de-pago-en-su-pagina-web","status":"publish","type":"post","link":"https:\/\/www.notaoficial.com\/s\/2020\/02\/21\/cines-unidos-incluye-nuevo-metodo-de-pago-en-su-pagina-web\/","title":{"rendered":"Cines Unidos incluye nuevo m\u00e9todo de pago en su p\u00e1gina WEB"},"content":{"rendered":"<p>Ahora en CINESUNIDOS.COM los invitados podr\u00e1n realizar la compra de boletos y carameler\u00eda con su tarjeta de d\u00e9bito Mercantil. Esta nueva modalidad est\u00e1 disponible para todas las salas del pa\u00eds.<\/p>\n<p>\u201cCines Unidos est\u00e1 orientado a ofrecer una experiencia completa y de alta calidad para nuestros invitados en todos los sentidos. Siempre buscamos innovar, evolucionando la manera de realizar las compras a trav\u00e9s de la WEB y brindar la mayor cantidad de opciones de pago f\u00e1ciles y confiables\u201d, destac\u00f3 Alberto Carrasquero, Vicepresidente de Operaciones y Mercadeo de Cines Unidos.<\/p>\n<p>El proceso es sencillo, el usuario debe ingresar en CINESUNIDOS.COM, elegir la pel\u00edcula y productos de carameler\u00eda de su preferencia y al momento de pagar, seleccionar la opci\u00f3n Mercantil. Luego, debe ingresar los datos de la tarjeta de d\u00e9bito Mercantil y su clave telef\u00f3nica, aceptar los t\u00e9rminos y condiciones para procesar el pago y \u00a1listo! Con la incorporaci\u00f3n de este nuevo m\u00e9todo de pago, los invitados podr\u00e1n hacer sus transacciones de manera c\u00f3moda y r\u00e1pida.<\/p>\n<p>Cines Unidos tambi\u00e9n cuenta con ViPPO, una billetera virtual a la que el usuario puede cargar saldo desde cualquier cuenta bancaria para adquirir entradas y productos de carameler\u00eda en la p\u00e1gina web de Cines Unidos.<\/p>\n<p>La empresa con m\u00e1s de 70 a\u00f1os de historia, sigue innovando en el pa\u00eds y trabajando para brindarle a los usuarios una experiencia r\u00e1pida y segura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ahora en CINESUNIDOS.COM los invitados podr\u00e1n realizar la compra de boletos y carameler\u00eda con su tarjeta de d\u00e9bito Mercantil. Esta nueva modalidad est\u00e1 disponible para todas las salas del pa\u00eds. \u201cCines Unidos est\u00e1 orientado a ofrecer una experiencia completa y de alta calidad para nuestros invitados en todos los sentidos. Siempre buscamos innovar, evolucionando la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7711,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4747,93,2],"tags":[4770],"wppr_data":[],"_links":{"self":[{"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/posts\/7706"}],"collection":[{"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/comments?post=7706"}],"version-history":[{"count":1,"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/posts\/7706\/revisions"}],"predecessor-version":[{"id":7713,"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/posts\/7706\/revisions\/7713"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/media\/7711"}],"wp:attachment":[{"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/media?parent=7706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/categories?post=7706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/tags?post=7706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}