{"id":7709,"date":"2020-02-21T23:19:03","date_gmt":"2020-02-22T03:19:03","guid":{"rendered":"http:\/\/www.notaoficial.com\/s\/?p=7709"},"modified":"2020-02-21T20:26:39","modified_gmt":"2020-02-22T00:26:39","slug":"espias-a-escondidas-una-divertida-historia-de-espionaje-llega-a-cines-unidos","status":"publish","type":"post","link":"https:\/\/www.notaoficial.com\/s\/2020\/02\/21\/espias-a-escondidas-una-divertida-historia-de-espionaje-llega-a-cines-unidos\/","title":{"rendered":"\u2018\u2018Esp\u00edas a Escondidas\u201d una divertida historia de espionaje llega a Cines Unidos"},"content":{"rendered":"<p>Cines Unidos anuncia el estreno de \u201cEsp\u00edas a escondidas\u201d, una comedia animada que se desarrolla en el explosivo mundo del espionaje internacional.<\/p>\n<p>El esp\u00eda m\u00e1s genial del mundo, Lance Sterling y Walter Ben\u00edtez son casi opuestos. Lance es cool, encantador y elegante. Walter\u2026 no. Pero lo que a Walter le falta de habilidades sociales, lo compensa con inteligencia e inventiva: es el genio cient\u00edfico que crea los artefactos que Lance usa en sus misiones. Pero cuando las cosas dan un giro inesperado, de pronto Walter y Lance tienen que confiar uno en el otro de una forma completamente nueva. Y si esta pareja dispareja no aprende a trabajar en equipo, el mundo entero est\u00e1 en peligro.<\/p>\n<p>Troy Quane y Nick Bruno hacen un trabajo fant\u00e1stico como directores de esta parodia animada del g\u00e9nero de los agentes secretos. Las pel\u00edculas dise\u00f1adas en 3D gozan de considerable respaldo entre la audiencia venezolana, y \u201cEsp\u00edas a escondidas\u201d es ideal para divertirse con familia y amigos ante la pantalla grande con una historia que va de la comedia a la ciencia ficci\u00f3n.<\/p>\n<p>\u201cEsp\u00edas a escondidas\u201d llega a las salas de Cines Unidos, ubicadas en las principales ciudades del pa\u00eds, desde el pr\u00f3ximo viernes 21 de febrero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cines Unidos anuncia el estreno de \u201cEsp\u00edas a escondidas\u201d, una comedia animada que se desarrolla en el explosivo mundo del espionaje internacional. El esp\u00eda m\u00e1s genial del mundo, Lance Sterling y Walter Ben\u00edtez son casi opuestos. Lance es cool, encantador y elegante. Walter\u2026 no. Pero lo que a Walter le falta de habilidades sociales, lo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7717,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4747,93,2],"tags":[4770,8475,8474],"wppr_data":[],"_links":{"self":[{"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/posts\/7709"}],"collection":[{"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/comments?post=7709"}],"version-history":[{"count":1,"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/posts\/7709\/revisions"}],"predecessor-version":[{"id":7718,"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/posts\/7709\/revisions\/7718"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/media\/7717"}],"wp:attachment":[{"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/media?parent=7709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/categories?post=7709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/tags?post=7709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}