{"id":8157,"date":"2020-06-14T03:31:46","date_gmt":"2020-06-14T07:31:46","guid":{"rendered":"https:\/\/www.notaoficial.com\/s\/?p=8157"},"modified":"2020-06-14T01:37:24","modified_gmt":"2020-06-14T05:37:24","slug":"cnn-worldwide-unifica-su-estrategia-comercial-global","status":"publish","type":"post","link":"https:\/\/www.notaoficial.com\/s\/2020\/06\/14\/cnn-worldwide-unifica-su-estrategia-comercial-global\/","title":{"rendered":"CNN Worldwide unifica su estrategia comercial global"},"content":{"rendered":"<p style=\"text-align: center;\">Por Isaac Sult\u00e1n Cohen<\/p>\n<div><strong>CNN Worldwide\u00a0<\/strong>ha nombrado a\u00a0<strong>Rani Raad<\/strong>\u00a0como\u00a0<strong>Presidente de CNN Commercial<\/strong>, en una nueva posici\u00f3n global para ampliar el flujo de nuevos negocios de la compa\u00f1\u00eda e incrementar el valor que CNN provee a sus socios comerciales alrededor del mundo.<br \/>\nAl centralizar la direcci\u00f3n y la actividad comercial en una sola operaci\u00f3n, CNN est\u00e1 creando un acercamiento m\u00e1s integrado, \u00e1gil y global a la manera en la que eval\u00faa las necesidades del mercado, desarrolla soluciones y trabaja con sus socios.<\/div>\n<div>\nPara lograr esto y asegurarse de que CNN est\u00e9 en la mejor posici\u00f3n para continuar su \u00e9xito comercial en esta d\u00e9cada, Raad trabajar\u00e1 de cerca con WarnerMedia Sales and International en las actividades de publicidad y distribuci\u00f3n, dirigir negocios internacionales a trav\u00e9s de CNN International Commercial, optimizar las operaciones de ingresos directamente controlados de CNN Worldwide, y maximizar el potencial comercial del desarrollo de nuevos productos.<\/div>\n<div>\nEn vigor de manera inmediata, Raad le reporta directamente a Jeff Zucker, Presidente de WarnerMedia News and Sports, y Presidente de CNN Worldwide.<\/div>\n<div>\n\u201c<em>Nunca ha habido un momento m\u00e1s importante que \u00e9ste para ser estrat\u00e9gicos y tener un prop\u00f3sito acerca de la generaci\u00f3n de ingresos a trav\u00e9s de las plataformas de CNN Worldwide,<\/em>\u201d coment\u00f3 Zucker. \u201c<em>Al alinear al Rani y su equipo de manera m\u00e1s cercana con el resto de la estructura de CNN, no hay duda de que har\u00e1 una gran diferencia en nuestra habilidad para encontrar nuevas maneras de hacer negocios y generar\u00e1 mayores oportunidades para nuestros clientes alrededor del mundo.<\/em>\u201d<\/div>\n<div>\nRaad, veterano en CNN con m\u00e1s de 22 a\u00f1os, comenz\u00f3 su carrera en la compa\u00f1\u00eda en Nueva York antes de ocupar una variedad de cargos senior internacionales en CNN y WarnerMedia. En 2013, Raad combin\u00f3 todas las operaciones de CNN fuera de los Estados Unidos en la divisi\u00f3n de CNN International Commercial (CNNIC), incluyendo publicidad, patrocinios, ventas de contenido y licencias,\u00a0<em>Out of Home<\/em>, marketing, y audiencias y data.<\/div>\n<div>\nDesde entonces, como presidente de CNNIC, Raad ha desarrollado el negocio al presentar una estrategia multiplataforma y centrada en data con capacidades digitales aumentadas, hecho a la medida para un amplio rango de clientes y necesidades de mercado en m\u00e1s de 200 pa\u00edses y territorios.<\/div>\n<div>\nRaad coment\u00f3: \u201c<em>No creo haber visto antes un momento como este en que CNN fuera tan influyente tanto en Estados Unidos como internacionalmente. Una era de cambios estructurales en el mercado de medios, el incremento de la demanda de noticias verificadas y el impacto econ\u00f3mico del COVID-19 ha cambiado de manera fundamental la manera en la que necesitamos trabajar con nuestros socios de negocio. Con nuestra marca premium, soluciones sofisticadas, y alcance mundial, ahora es m\u00e1s importante que nunca que nuestros socios de negocios tengan acceso a la suite completa de capacidades globales de CNN, sin importar d\u00f3nde est\u00e9n\u00bb.<\/em><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Isaac Sult\u00e1n Cohen CNN Worldwide\u00a0ha nombrado a\u00a0Rani Raad\u00a0como\u00a0Presidente de CNN Commercial, en una nueva posici\u00f3n global para ampliar el flujo de nuevos negocios de la compa\u00f1\u00eda e incrementar el valor que CNN provee a sus socios comerciales alrededor del mundo. Al centralizar la direcci\u00f3n y la actividad comercial en una sola operaci\u00f3n, CNN est\u00e1 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8162,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[146],"tags":[3641,8794,8677,8793],"wppr_data":{"cwp_meta_box_check":"No"},"_links":{"self":[{"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/posts\/8157"}],"collection":[{"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/comments?post=8157"}],"version-history":[{"count":1,"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/posts\/8157\/revisions"}],"predecessor-version":[{"id":8164,"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/posts\/8157\/revisions\/8164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/media\/8162"}],"wp:attachment":[{"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/media?parent=8157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/categories?post=8157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.notaoficial.com\/s\/wp-json\/wp\/v2\/tags?post=8157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}